{"id":1470,"date":"2018-02-26T18:48:19","date_gmt":"2018-02-26T17:48:19","guid":{"rendered":"https:\/\/cftc-dartyidf.fr\/?p=1470"},"modified":"2018-02-27T00:43:48","modified_gmt":"2018-02-26T23:43:48","slug":"regles-elementaires","status":"publish","type":"post","link":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/","title":{"rendered":"R\u00e8gles \u00e9l\u00e9mentaires"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\">Chaque salari\u00e9 doit respecter les r\u00e8gles \u00e9l\u00e9mentaires de savoir-vivre et de savoir-\u00eatre en collectivit\u00e9.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Toute rixe, injure, insulte, ainsi que tout comportement agressif et d&#8217;incivilit\u00e9 sont interdits dans l&#8217;UES Darty Paris Ile-de-France, a fortiori lorsqu&#8217;ils sont p\u00e9nablement sanctionnables.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Il en est de m\u00eame de tout comportement raciste, x\u00e9nophobe, sexiste et\/ou discriminant au sens des dispositions du code du travail et du code p\u00e9nal, ainsi que de toute forme de harc\u00e8lement et de discrimination.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Notamment tout comportement ou diff\u00e9rence de traitement entre responsable hi\u00e9rarchique et collaborateurs, mais \u00e9galement entre collaborateurs, fond\u00e9 sur un motif discriminant tel que, par exemple, le sexe, l&#8217;origine ou la religion, est strictement prohib\u00e9 et pourra faire l&#8217;objet de sanctions disciplinaires.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\"><em>R\u00e9glement int\u00e9rieur UES Darty Ile-de-France<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chaque salari\u00e9 doit respecter les r\u00e8gles \u00e9l\u00e9mentaires de savoir-vivre et de savoir-\u00eatre en collectivit\u00e9. Toute rixe, injure, insulte, ainsi que tout comportement agressif et d&#8217;incivilit\u00e9 sont interdits dans l&#8217;UES Darty &#8230; <a title=\"R\u00e8gles \u00e9l\u00e9mentaires\" class=\"read-more\" href=\"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/\" aria-label=\"En savoir plus sur R\u00e8gles \u00e9l\u00e9mentaires\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":1471,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"generate_page_header":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-1470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accueil","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e8gles \u00e9l\u00e9mentaires - CFTC-Darty IDF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e8gles \u00e9l\u00e9mentaires - CFTC-Darty IDF\" \/>\n<meta property=\"og:description\" content=\"Chaque salari\u00e9 doit respecter les r\u00e8gles \u00e9l\u00e9mentaires de savoir-vivre et de savoir-\u00eatre en collectivit\u00e9. Toute rixe, injure, insulte, ainsi que tout comportement agressif et d&#8217;incivilit\u00e9 sont interdits dans l&#8217;UES Darty ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/\" \/>\n<meta property=\"og:site_name\" content=\"CFTC-Darty IDF\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-26T17:48:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-26T23:43:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cftc-dartyidf.fr\/wp-content\/uploads\/2018\/02\/savoirvivre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"624\" \/>\n\t<meta property=\"og:image:height\" content=\"624\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webcsfv\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"webcsfv\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/index.php\\\/2018\\\/02\\\/26\\\/regles-elementaires\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/index.php\\\/2018\\\/02\\\/26\\\/regles-elementaires\\\/\"},\"author\":{\"name\":\"webcsfv\",\"@id\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/#\\\/schema\\\/person\\\/71ee82537a022b7e374bcb7943ef2cd2\"},\"headline\":\"R\u00e8gles \u00e9l\u00e9mentaires\",\"datePublished\":\"2018-02-26T17:48:19+00:00\",\"dateModified\":\"2018-02-26T23:43:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/index.php\\\/2018\\\/02\\\/26\\\/regles-elementaires\\\/\"},\"wordCount\":137,\"image\":{\"@id\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/index.php\\\/2018\\\/02\\\/26\\\/regles-elementaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/savoirvivre.jpg\",\"articleSection\":[\"Accueil\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/index.php\\\/2018\\\/02\\\/26\\\/regles-elementaires\\\/\",\"url\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/index.php\\\/2018\\\/02\\\/26\\\/regles-elementaires\\\/\",\"name\":\"R\u00e8gles \u00e9l\u00e9mentaires - CFTC-Darty IDF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/index.php\\\/2018\\\/02\\\/26\\\/regles-elementaires\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/index.php\\\/2018\\\/02\\\/26\\\/regles-elementaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/savoirvivre.jpg\",\"datePublished\":\"2018-02-26T17:48:19+00:00\",\"dateModified\":\"2018-02-26T23:43:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/#\\\/schema\\\/person\\\/71ee82537a022b7e374bcb7943ef2cd2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/index.php\\\/2018\\\/02\\\/26\\\/regles-elementaires\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cftc-dartyidf.fr\\\/index.php\\\/2018\\\/02\\\/26\\\/regles-elementaires\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/index.php\\\/2018\\\/02\\\/26\\\/regles-elementaires\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/savoirvivre.jpg\",\"contentUrl\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/savoirvivre.jpg\",\"width\":624,\"height\":624},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/index.php\\\/2018\\\/02\\\/26\\\/regles-elementaires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e8gles \u00e9l\u00e9mentaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/#website\",\"url\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/\",\"name\":\"CFTC-Darty IDF\",\"description\":\"Le site de la section syndicale CFTC chez Darty IDF\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/#\\\/schema\\\/person\\\/71ee82537a022b7e374bcb7943ef2cd2\",\"name\":\"webcsfv\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d8bf08c8feaca537ce41c2b95cec6c85a8036a1687877b5eb7cb09dcb9b6f06?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d8bf08c8feaca537ce41c2b95cec6c85a8036a1687877b5eb7cb09dcb9b6f06?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d8bf08c8feaca537ce41c2b95cec6c85a8036a1687877b5eb7cb09dcb9b6f06?s=96&d=mm&r=g\",\"caption\":\"webcsfv\"},\"url\":\"https:\\\/\\\/cftc-dartyidf.fr\\\/index.php\\\/author\\\/webcsfv\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e8gles \u00e9l\u00e9mentaires - CFTC-Darty IDF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e8gles \u00e9l\u00e9mentaires - CFTC-Darty IDF","og_description":"Chaque salari\u00e9 doit respecter les r\u00e8gles \u00e9l\u00e9mentaires de savoir-vivre et de savoir-\u00eatre en collectivit\u00e9. Toute rixe, injure, insulte, ainsi que tout comportement agressif et d&#8217;incivilit\u00e9 sont interdits dans l&#8217;UES Darty ... Lire plus","og_url":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/","og_site_name":"CFTC-Darty IDF","article_published_time":"2018-02-26T17:48:19+00:00","article_modified_time":"2018-02-26T23:43:48+00:00","og_image":[{"width":624,"height":624,"url":"https:\/\/cftc-dartyidf.fr\/wp-content\/uploads\/2018\/02\/savoirvivre.jpg","type":"image\/jpeg"}],"author":"webcsfv","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"webcsfv","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/#article","isPartOf":{"@id":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/"},"author":{"name":"webcsfv","@id":"https:\/\/cftc-dartyidf.fr\/#\/schema\/person\/71ee82537a022b7e374bcb7943ef2cd2"},"headline":"R\u00e8gles \u00e9l\u00e9mentaires","datePublished":"2018-02-26T17:48:19+00:00","dateModified":"2018-02-26T23:43:48+00:00","mainEntityOfPage":{"@id":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/"},"wordCount":137,"image":{"@id":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/#primaryimage"},"thumbnailUrl":"https:\/\/cftc-dartyidf.fr\/wp-content\/uploads\/2018\/02\/savoirvivre.jpg","articleSection":["Accueil"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/","url":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/","name":"R\u00e8gles \u00e9l\u00e9mentaires - CFTC-Darty IDF","isPartOf":{"@id":"https:\/\/cftc-dartyidf.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/#primaryimage"},"image":{"@id":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/#primaryimage"},"thumbnailUrl":"https:\/\/cftc-dartyidf.fr\/wp-content\/uploads\/2018\/02\/savoirvivre.jpg","datePublished":"2018-02-26T17:48:19+00:00","dateModified":"2018-02-26T23:43:48+00:00","author":{"@id":"https:\/\/cftc-dartyidf.fr\/#\/schema\/person\/71ee82537a022b7e374bcb7943ef2cd2"},"breadcrumb":{"@id":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/#primaryimage","url":"https:\/\/cftc-dartyidf.fr\/wp-content\/uploads\/2018\/02\/savoirvivre.jpg","contentUrl":"https:\/\/cftc-dartyidf.fr\/wp-content\/uploads\/2018\/02\/savoirvivre.jpg","width":624,"height":624},{"@type":"BreadcrumbList","@id":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/26\/regles-elementaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cftc-dartyidf.fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e8gles \u00e9l\u00e9mentaires"}]},{"@type":"WebSite","@id":"https:\/\/cftc-dartyidf.fr\/#website","url":"https:\/\/cftc-dartyidf.fr\/","name":"CFTC-Darty IDF","description":"Le site de la section syndicale CFTC chez Darty IDF","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cftc-dartyidf.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/cftc-dartyidf.fr\/#\/schema\/person\/71ee82537a022b7e374bcb7943ef2cd2","name":"webcsfv","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3d8bf08c8feaca537ce41c2b95cec6c85a8036a1687877b5eb7cb09dcb9b6f06?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3d8bf08c8feaca537ce41c2b95cec6c85a8036a1687877b5eb7cb09dcb9b6f06?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3d8bf08c8feaca537ce41c2b95cec6c85a8036a1687877b5eb7cb09dcb9b6f06?s=96&d=mm&r=g","caption":"webcsfv"},"url":"https:\/\/cftc-dartyidf.fr\/index.php\/author\/webcsfv\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/cftc-dartyidf.fr\/wp-content\/uploads\/2018\/02\/savoirvivre.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8n98f-nI","jetpack-related-posts":[{"id":1380,"url":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/01\/25\/le-mot-du-directeur-general\/","url_meta":{"origin":1470,"position":0},"title":"Le mot du Directeur G\u00e9n\u00e9ral","author":"webcsfv","date":"25\/01\/2018","format":false,"excerpt":"La Fnac et Darty\u00a0: leurs ressemblances comme leurs singularit\u00e9s appelaient \u00e0 l\u2019alliance de ces deux enseignes embl\u00e9matiques. Marques historiques aux caract\u00e8res forts, elles partagent une culture du service hors pair, une image ch\u00e8re au c\u0153ur des Fran\u00e7ais, le go\u00fbt de l\u2019innovation, un r\u00e9seau de distribution puissant, une empreinte d\u00e9lib\u00e9r\u00e9ment omnicanale\u2026","rel":"","context":"Dans &quot;Accueil&quot;","block_context":{"text":"Accueil","link":"https:\/\/cftc-dartyidf.fr\/index.php\/category\/accueil\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":123,"url":"https:\/\/cftc-dartyidf.fr\/index.php\/2016\/11\/09\/mutualisation-offre-demploi-darty-fnac\/","url_meta":{"origin":1470,"position":1},"title":"Mutualisation offres d&#8217;emploi Darty et Fnac","author":"webcsfv","date":"09\/11\/2016","format":false,"excerpt":"Darty et Fnac viennent de mutualiser leurs offres d'emploi afin de permettre de g\u00e9n\u00e9rer plus d'opportunit\u00e9s pour les collaborateurs des deux enseignes. En effet, depuis le 03 novembre les postes \u00e0 pourvoir sont ouverts \u00e0 l'ensemble des salari\u00e9s Darty Fnac et pour y acc\u00e9der ces derniers peuvent toujours utiliser les\u2026","rel":"","context":"Dans &quot;Revue de presse&quot;","block_context":{"text":"Revue de presse","link":"https:\/\/cftc-dartyidf.fr\/index.php\/category\/actualite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/cftc-dartyidf.fr\/wp-content\/uploads\/2016\/11\/offre-emploi.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1349,"url":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/01\/17\/interdiction-de-vapoter\/","url_meta":{"origin":1470,"position":2},"title":"Interdiction de vapoter","author":"webcsfv","date":"17\/01\/2018","format":false,"excerpt":"L'utilisation de la cigarette \u00e9lectronique ou \"vapotage\" est interdit en entreprise depuis la loi de modernisation de notre syst\u00e8me de sant\u00e9 du 26 Janvier 2016. Le d\u00e9cret n\u00b0 2017-633 du 25 avril 207 permet d'en fixer les conditions d'application. \u00a0 La r\u00e9glementation Aux termes de ce texte, il est interdit\u2026","rel":"","context":"Dans &quot;Accueil&quot;","block_context":{"text":"Accueil","link":"https:\/\/cftc-dartyidf.fr\/index.php\/category\/accueil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/cftc-dartyidf.fr\/wp-content\/uploads\/2018\/01\/vapoter.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1614,"url":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/06\/21\/barometre-du-sav\/","url_meta":{"origin":1470,"position":3},"title":"Barom\u00e8tre du SAV","author":"webcsfv","date":"21\/06\/2018","format":false,"excerpt":"Fnac Darty publie le premier Barom\u00e8tre du SAV , une \u00e9tude in\u00e9dite sur la dur\u00e9e de vie des produits. Fnac Darty a lanc\u00e9 une vaste \u00e9tude afin de mieux informer le public sur la dur\u00e9e de vie des \u00e9quipements \u00e9lectrom\u00e9nagers et multim\u00e9dia \u00e0 l\u2019aide\u00a0 d\u2019indicateurs in\u00e9dits. Ce barom\u00e8tre sera renouvel\u00e9\u2026","rel":"","context":"Dans &quot;Accueil&quot;","block_context":{"text":"Accueil","link":"https:\/\/cftc-dartyidf.fr\/index.php\/category\/accueil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/cftc-dartyidf.fr\/wp-content\/uploads\/2018\/06\/barometre-sav-fnac-darty-07.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cftc-dartyidf.fr\/wp-content\/uploads\/2018\/06\/barometre-sav-fnac-darty-07.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cftc-dartyidf.fr\/wp-content\/uploads\/2018\/06\/barometre-sav-fnac-darty-07.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cftc-dartyidf.fr\/wp-content\/uploads\/2018\/06\/barometre-sav-fnac-darty-07.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1291,"url":"https:\/\/cftc-dartyidf.fr\/index.php\/2017\/12\/10\/enrique-martinez-fnac-darty-carrefour-allons-etre-plus-puissants\/","url_meta":{"origin":1470,"position":4},"title":"Enrique Martinez (Fnac Darty) : &#8220;Avec Carrefour, nous allons \u00eatre encore plus puissants&#8221;","author":"webcsfv","date":"10\/12\/2017","format":false,"excerpt":"Enrique Martinez, directeur g\u00e9n\u00e9ral de Fnac Darty, \u00e9tait L'invit\u00e9 de l'interview \u00e9co mardi pour \u00e9voquer l'alliance sign\u00e9e avec le groupe Carrefour. Ils n\u00e9gocieront ensemble l'achat de leurs produits \u00e9lectrom\u00e9nagers et \u00e9lectroniques grand public en France. Les groupes Fnac Darty et Carrefour ont sign\u00e9 mardi 5 d\u00e9cembre une alliance pour n\u00e9gocier\u2026","rel":"","context":"Dans &quot;Accueil&quot;","block_context":{"text":"Accueil","link":"https:\/\/cftc-dartyidf.fr\/index.php\/category\/accueil\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466,"url":"https:\/\/cftc-dartyidf.fr\/index.php\/2018\/02\/20\/alcool-lieu-de-travail\/","url_meta":{"origin":1470,"position":5},"title":"Alcool sur le lieu de travail","author":"webcsfv","date":"20\/02\/2018","format":false,"excerpt":"Il est interdit d'introduire ou de consommer, sans autorisation des boissons alcoolis\u00e9es dans les locaux de l'UES Darty Paris Ile-de-France. Article 9.3 Le cas \u00e9ch\u00e9ant, il pourra \u00eatre demand\u00e9 aux salari\u00e9s qui : conduisent un engin, une voiture de soci\u00e9t\u00e9 ou une voiture de location pour le compte de l'UES\u2026","rel":"","context":"Dans &quot;Accueil&quot;","block_context":{"text":"Accueil","link":"https:\/\/cftc-dartyidf.fr\/index.php\/category\/accueil\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/cftc-dartyidf.fr\/wp-content\/uploads\/2018\/02\/alcool.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cftc-dartyidf.fr\/wp-content\/uploads\/2018\/02\/alcool.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cftc-dartyidf.fr\/wp-content\/uploads\/2018\/02\/alcool.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cftc-dartyidf.fr\/wp-content\/uploads\/2018\/02\/alcool.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/cftc-dartyidf.fr\/index.php\/wp-json\/wp\/v2\/posts\/1470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cftc-dartyidf.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cftc-dartyidf.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cftc-dartyidf.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cftc-dartyidf.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1470"}],"version-history":[{"count":6,"href":"https:\/\/cftc-dartyidf.fr\/index.php\/wp-json\/wp\/v2\/posts\/1470\/revisions"}],"predecessor-version":[{"id":1481,"href":"https:\/\/cftc-dartyidf.fr\/index.php\/wp-json\/wp\/v2\/posts\/1470\/revisions\/1481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cftc-dartyidf.fr\/index.php\/wp-json\/wp\/v2\/media\/1471"}],"wp:attachment":[{"href":"https:\/\/cftc-dartyidf.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cftc-dartyidf.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cftc-dartyidf.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}